{"id":31101,"date":"2024-06-10T18:07:27","date_gmt":"2024-06-10T16:07:27","guid":{"rendered":"https:\/\/soldac-project.eu\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/"},"modified":"2024-06-10T22:32:09","modified_gmt":"2024-06-10T20:32:09","slug":"el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas","status":"publish","type":"post","link":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/","title":{"rendered":"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">La unidad Espectro Solar Completo (ESC) del sistema SolDAC gestiona la radiaci\u00f3n solar incidente dividiendo espectralmente los fotones incidentes en dos flujos: el \u00abfr\u00edo\u00bb y el \u00abcaliente\u00bb. El flujo fr\u00edo de fotones comprende los fotones comprendidos entre 300 nm y 1100 nm y el flujo caliente los de la regi\u00f3n del infrarrojo cercano a partir de 1100 nm. Para ello, la irradiancia incidente se concentra mediante un concentrador Fresnel compuesto por 10 reflectores de forma parab\u00f3lica que enfocan la luz solar en el plano receptor. Los receptores desempe\u00f1an una doble funci\u00f3n: (1) Convertir y adaptar la intensidad concentrada incidente lineal en un foco puntual que posteriormente es guiado por un haz de fibras \u00f3pticas; (2) Dividir el espectro concentrado incidente mediante un filtro l\u00edquido de absorci\u00f3n que absorbe el flujo caliente de fotones para producir calor y transmite los de menor longitud de onda para ser guiados por la luz. El flujo caliente de fotones es utilizado posteriormente por la unidad de captura directa de aire del sistema SolDAC para mejorar la adsorci\u00f3n de CO<sub>2<\/sub> y el flujo fr\u00edo de fotones es convertido en electrones bien por una c\u00e9lula fotovoltaica o por un foto\u00e1nodo de la unidad fotoelectroqu\u00edmica de SolDAC.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"325\" height=\"331\" src=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_1_10_junio.jpg\" alt=\"\" class=\"wp-image-31094\" srcset=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_1_10_junio.jpg 325w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_1_10_junio-295x300.jpg 295w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_1_10_junio-50x51.jpg 50w\" sizes=\"(max-width: 325px) 100vw, 325px\" \/><figcaption class=\"wp-element-caption\">Figura 1. Unidad de Espectro Solar Completo<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">En la actualidad, se han fabricado y ensamblado todos los componentes del ESC, incluidos los sistemas de seguimiento y control. La figura 1 muestra el prototipo fabricado e incorporado en las instalaciones de la Universidad de Lleida. En la fotograf\u00eda se aprecia la plataforma de reflectores, inclinada 40\u00ba, y cuatro receptores (dos de ellos con los haces de fibra \u00f3ptica conectados). Actualmente, estamos llevando a cabo la caracterizaci\u00f3n t\u00e9rmica y espectral completa del ESC antes de ser acoplado y evaluado con el resto de las unidades SolDAC: recolector de agua, captura directa de aire y reactor fotoelectroqu\u00edmico. La figura 2 ilustra el receptor de divisi\u00f3n espectral.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"734\" height=\"345\" src=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_2_10_junio.jpg\" alt=\"\" class=\"wp-image-31097\" srcset=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_2_10_junio.jpg 734w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_2_10_junio-300x141.jpg 300w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_2_10_junio-50x24.jpg 50w\" sizes=\"(max-width: 734px) 100vw, 734px\" \/><figcaption class=\"wp-element-caption\">Figura 2. Receptor de divisi\u00f3n espectral<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><em>Escrito por <a href=\"https:\/\/www.udl.cat\/ca\/\">UdL<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La unidad Espectro Solar Completo (ESC) del sistema SolDAC gestiona la radiaci\u00f3n solar incidente dividiendo espectralmente los fotones incidentes en dos flujos: el \u00abfr\u00edo\u00bb y el \u00abcaliente\u00bb. El flujo fr\u00edo de fotones comprende los fotones comprendidos entre 300 nm y 1100 nm y el flujo caliente los de la regi\u00f3n del infrarrojo cercano a partir &#8230; <a title=\"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas\" class=\"read-more\" href=\"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/\" aria-label=\"Leer m\u00e1s sobre El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":22,"featured_media":31096,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[675],"tags":[],"class_list":["post-31101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas - SolDAC<\/title>\n<meta name=\"description\" content=\"La unidad Espectro Solar Completo (ESC) del sistema SolDAC gestiona la radiaci\u00f3n solar incidente dividiendo espectralmente los fotones incidentes en dos flujos: el \u00abfr\u00edo\u00bb y el \u00abcaliente\u00bb. El flujo fr\u00edo de fotones comprende los fotones comprendidos entre 300 nm y 1100 nm y el flujo caliente los de la regi\u00f3n del infrarrojo cercano a partir de 1100 nm.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas - SolDAC\" \/>\n<meta property=\"og:description\" content=\"La unidad Espectro Solar Completo (ESC) del sistema SolDAC gestiona la radiaci\u00f3n solar incidente dividiendo espectralmente los fotones incidentes en dos flujos: el \u00abfr\u00edo\u00bb y el \u00abcaliente\u00bb. El flujo fr\u00edo de fotones comprende los fotones comprendidos entre 300 nm y 1100 nm y el flujo caliente los de la regi\u00f3n del infrarrojo cercano a partir de 1100 nm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/\" \/>\n<meta property=\"og:site_name\" content=\"SolDAC\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T16:07:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-10T20:32:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_1_10_junio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"325\" \/>\n\t<meta property=\"og:image:height\" content=\"331\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cintiaescandel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cintiaescandel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/\"},\"author\":{\"name\":\"cintiaescandel\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#\\\/schema\\\/person\\\/66bdc622ff88cc2e1a4a4592386b711f\"},\"headline\":\"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas\",\"datePublished\":\"2024-06-10T16:07:27+00:00\",\"dateModified\":\"2024-06-10T20:32:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/\"},\"wordCount\":342,\"publisher\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/06\\\/SolDAC_1_10_junio.jpg\",\"articleSection\":[\"Tecnolog\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/\",\"url\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/\",\"name\":\"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas - SolDAC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/06\\\/SolDAC_1_10_junio.jpg\",\"datePublished\":\"2024-06-10T16:07:27+00:00\",\"dateModified\":\"2024-06-10T20:32:09+00:00\",\"description\":\"La unidad Espectro Solar Completo (ESC) del sistema SolDAC gestiona la radiaci\u00f3n solar incidente dividiendo espectralmente los fotones incidentes en dos flujos: el \u00abfr\u00edo\u00bb y el \u00abcaliente\u00bb. El flujo fr\u00edo de fotones comprende los fotones comprendidos entre 300 nm y 1100 nm y el flujo caliente los de la regi\u00f3n del infrarrojo cercano a partir de 1100 nm.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/06\\\/SolDAC_1_10_junio.jpg\",\"contentUrl\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/06\\\/SolDAC_1_10_junio.jpg\",\"width\":325,\"height\":331},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/\",\"name\":\"SolDAC\",\"description\":\"Full Spectrum Solar Direct Air Caputure &amp; Conversion\",\"publisher\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#organization\",\"name\":\"SolDAC\",\"url\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2022\\\/11\\\/SolDAC_Logo_RGB_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2022\\\/11\\\/SolDAC_Logo_RGB_COLOR.png\",\"width\":2084,\"height\":693,\"caption\":\"SolDAC\"},\"image\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#\\\/schema\\\/person\\\/66bdc622ff88cc2e1a4a4592386b711f\",\"name\":\"cintiaescandel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g\",\"caption\":\"cintiaescandel\"},\"url\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/author\\\/cintiaescandell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas - SolDAC","description":"La unidad Espectro Solar Completo (ESC) del sistema SolDAC gestiona la radiaci\u00f3n solar incidente dividiendo espectralmente los fotones incidentes en dos flujos: el \u00abfr\u00edo\u00bb y el \u00abcaliente\u00bb. El flujo fr\u00edo de fotones comprende los fotones comprendidos entre 300 nm y 1100 nm y el flujo caliente los de la regi\u00f3n del infrarrojo cercano a partir de 1100 nm.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/","og_locale":"es_ES","og_type":"article","og_title":"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas - SolDAC","og_description":"La unidad Espectro Solar Completo (ESC) del sistema SolDAC gestiona la radiaci\u00f3n solar incidente dividiendo espectralmente los fotones incidentes en dos flujos: el \u00abfr\u00edo\u00bb y el \u00abcaliente\u00bb. El flujo fr\u00edo de fotones comprende los fotones comprendidos entre 300 nm y 1100 nm y el flujo caliente los de la regi\u00f3n del infrarrojo cercano a partir de 1100 nm.","og_url":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/","og_site_name":"SolDAC","article_published_time":"2024-06-10T16:07:27+00:00","article_modified_time":"2024-06-10T20:32:09+00:00","og_image":[{"width":325,"height":331,"url":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_1_10_junio.jpg","type":"image\/jpeg"}],"author":"cintiaescandel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cintiaescandel","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/#article","isPartOf":{"@id":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/"},"author":{"name":"cintiaescandel","@id":"https:\/\/soldac-project.eu\/es\/#\/schema\/person\/66bdc622ff88cc2e1a4a4592386b711f"},"headline":"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas","datePublished":"2024-06-10T16:07:27+00:00","dateModified":"2024-06-10T20:32:09+00:00","mainEntityOfPage":{"@id":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/"},"wordCount":342,"publisher":{"@id":"https:\/\/soldac-project.eu\/es\/#organization"},"image":{"@id":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/#primaryimage"},"thumbnailUrl":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_1_10_junio.jpg","articleSection":["Tecnolog\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/","url":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/","name":"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas - SolDAC","isPartOf":{"@id":"https:\/\/soldac-project.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/#primaryimage"},"image":{"@id":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/#primaryimage"},"thumbnailUrl":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_1_10_junio.jpg","datePublished":"2024-06-10T16:07:27+00:00","dateModified":"2024-06-10T20:32:09+00:00","description":"La unidad Espectro Solar Completo (ESC) del sistema SolDAC gestiona la radiaci\u00f3n solar incidente dividiendo espectralmente los fotones incidentes en dos flujos: el \u00abfr\u00edo\u00bb y el \u00abcaliente\u00bb. El flujo fr\u00edo de fotones comprende los fotones comprendidos entre 300 nm y 1100 nm y el flujo caliente los de la regi\u00f3n del infrarrojo cercano a partir de 1100 nm.","breadcrumb":{"@id":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/#primaryimage","url":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_1_10_junio.jpg","contentUrl":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/06\/SolDAC_1_10_junio.jpg","width":325,"height":331},{"@type":"BreadcrumbList","@id":"https:\/\/soldac-project.eu\/es\/el-sistema-de-espectro-solar-completo-esta-listo-para-las-pruebas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soldac-project.eu\/es\/"},{"@type":"ListItem","position":2,"name":"El sistema de Espectro Solar Completo est\u00e1 listo para las pruebas"}]},{"@type":"WebSite","@id":"https:\/\/soldac-project.eu\/es\/#website","url":"https:\/\/soldac-project.eu\/es\/","name":"SolDAC","description":"Full Spectrum Solar Direct Air Caputure &amp; Conversion","publisher":{"@id":"https:\/\/soldac-project.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soldac-project.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/soldac-project.eu\/es\/#organization","name":"SolDAC","url":"https:\/\/soldac-project.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soldac-project.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2022\/11\/SolDAC_Logo_RGB_COLOR.png","contentUrl":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2022\/11\/SolDAC_Logo_RGB_COLOR.png","width":2084,"height":693,"caption":"SolDAC"},"image":{"@id":"https:\/\/soldac-project.eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/soldac-project.eu\/es\/#\/schema\/person\/66bdc622ff88cc2e1a4a4592386b711f","name":"cintiaescandel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g","caption":"cintiaescandel"},"url":"https:\/\/soldac-project.eu\/es\/author\/cintiaescandell\/"}]}},"_links":{"self":[{"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/posts\/31101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/comments?post=31101"}],"version-history":[{"count":3,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/posts\/31101\/revisions"}],"predecessor-version":[{"id":31104,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/posts\/31101\/revisions\/31104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/media\/31096"}],"wp:attachment":[{"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/media?parent=31101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/categories?post=31101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/tags?post=31101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}