{"id":30864,"date":"2024-03-12T12:47:36","date_gmt":"2024-03-12T11:47:36","guid":{"rendered":"https:\/\/soldac-project.eu\/3a-asamblea-general-de-soldac-en-messina-sicilia\/"},"modified":"2024-03-12T13:08:43","modified_gmt":"2024-03-12T12:08:43","slug":"3a-asamblea-general-de-soldac-en-messina-sicilia","status":"publish","type":"post","link":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/","title":{"rendered":"3\u00aa Asamblea General de SolDAC en Messina, Sicilia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">El pasado 29 de febrero y 1 de marzo se llev\u00f3 a cabo la 3\u00aa Asamblea General de SolDAC en Messina.<br\/>Tuvimos la oportunidad de seguir trabajando juntos, discutiendo sobre la mejor manera de acercar SolDAC a la sociedad.<\/p>\n\n<h2 class=\"wp-block-heading\">D\u00eda 1<\/h2>\n\n<p class=\"wp-block-paragraph\">En primer lugar, LOMARTOV present\u00f3 su Hito 9, una presentaci\u00f3n realizada por Mihaela Mirea sobre una primera visi\u00f3n de la implicaci\u00f3n social de SolDAC.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP6_2-1-1024x768.jpg\" alt=\"\" class=\"wp-image-30845\" srcset=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP6_2-1-1024x768.jpg 1024w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP6_2-1-300x225.jpg 300w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP6_2-1-768x576.jpg 768w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP6_2-1-1536x1152.jpg 1536w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP6_2-1-2048x1536.jpg 2048w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP6_2-1-50x38.jpg 50w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP6_2-1-1600x1200.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Posteriormente Edgar Contreras de LOMARTOV, explic\u00f3 el estado del WP6, orientaci\u00f3n y validaci\u00f3n del triple pilar de sostenibilidad.<br\/>El WP3, que versa sobre el DAC fue explicado por Isabella Cavalcante (UEDIN), Paul Wright y Harpreet Kaur (UDTAN) y Valeria Palomba (CNR-ITAE).<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP3_UEDIN_1-1024x536.jpg\" alt=\"\" class=\"wp-image-30848\" srcset=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP3_UEDIN_1-1024x536.jpg 1024w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP3_UEDIN_1-300x157.jpg 300w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP3_UEDIN_1-768x402.jpg 768w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP3_UEDIN_1-1536x804.jpg 1536w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP3_UEDIN_1-2048x1072.jpg 2048w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP3_UEDIN_1-50x26.jpg 50w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP3_UEDIN_1-1600x838.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">IREC (Sebasti\u00e1n Murcia) explic\u00f3 el progreso de la pila de conversi\u00f3n fotoel\u00e9ctrica desarrollada en el WP4.<br\/>El \u00faltimo WP del d\u00eda fue el WP7, donde COMET explic\u00f3 la parte de comunicaci\u00f3n y EIM la parte de explotaci\u00f3n. EIM lhizo hincapi\u00e9 en los Resultados Explotables clave y estableciendo reuniones bilaterales entre los responsables de los resultados explotables de cada WP.<br\/>Para finalizar el d\u00eda CNR-ITAE organiz\u00f3 una visita a sus laboratorios y pudimos conocer el trabajo que se realiza en SolDAC y en otros muchos proyectos.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Lab_visits_5-1024x768.jpg\" alt=\"\" class=\"wp-image-30851\" srcset=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Lab_visits_5-1024x768.jpg 1024w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Lab_visits_5-300x225.jpg 300w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Lab_visits_5-768x576.jpg 768w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Lab_visits_5-1536x1152.jpg 1536w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Lab_visits_5-2048x1536.jpg 2048w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Lab_visits_5-50x38.jpg 50w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Lab_visits_5-1600x1200.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\">D\u00eda 2<\/h2>\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s primer d\u00eda intenso, comenzamos el segundo y \u00faltimo d\u00eda con la explicaci\u00f3n del WP2 liderado por Daniel Chemisana (UdL). Pudimos comprobar con fotos y con sus explicaciones el estado del Sistema del espectro solar completo.<br\/>En el WP5, liderado por COMET se debati\u00f3 la mejor manera para la integraci\u00f3n de los tres sistemas (DAC, PEC y FSS) que se llevar\u00e1 a cabo este a\u00f1o.<br\/>Para finalizar con las presentaciones, Gisela Soley (COMET) explic\u00f3 el WP1 dedicado a la gesti\u00f3n y coordinaci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP1_COMET_4-1024x768.jpg\" alt=\"\" class=\"wp-image-30854\" srcset=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP1_COMET_4-1024x768.jpg 1024w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP1_COMET_4-300x225.jpg 300w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP1_COMET_4-768x576.jpg 768w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP1_COMET_4-1536x1152.jpg 1536w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP1_COMET_4-2048x1536.jpg 2048w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP1_COMET_4-50x38.jpg 50w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/WP1_COMET_4-1600x1200.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Para terminar, pudimos seguir la visita a las instalaciones del CNR-ITAE y terminar el tour por los laboratorios.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Other_labs_1-1024x768.jpg\" alt=\"\" class=\"wp-image-30857\" srcset=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Other_labs_1-1024x768.jpg 1024w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Other_labs_1-300x225.jpg 300w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Other_labs_1-768x576.jpg 768w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Other_labs_1-1536x1152.jpg 1536w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Other_labs_1-2048x1536.jpg 2048w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Other_labs_1-50x38.jpg 50w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Other_labs_1-1600x1200.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">\u00a1Damos las gracias a CNR-ITAE por acogernos en su sede y por mostrarnos el incre\u00edble trabajo que realizan sus investigadores!<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-1024x768.jpg\" alt=\"\" class=\"wp-image-30860\" srcset=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-1024x768.jpg 1024w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-300x225.jpg 300w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-768x576.jpg 768w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-1536x1152.jpg 1536w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-2048x1536.jpg 2048w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-50x38.jpg 50w, https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-1600x1200.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">\u00a1Seguimos trabajando en SolDAC y esperamos poder vernos en persona pronto en los pr\u00f3ximos eventos y Asambleas Generales!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 29 de febrero y 1 de marzo se llev\u00f3 a cabo la 3\u00aa Asamblea General de SolDAC en Messina.Tuvimos la oportunidad de seguir trabajando juntos, discutiendo sobre la mejor manera de acercar SolDAC a la sociedad. D\u00eda 1 En primer lugar, LOMARTOV present\u00f3 su Hito 9, una presentaci\u00f3n realizada por Mihaela Mirea sobre &#8230; <a title=\"3\u00aa Asamblea General de SolDAC en Messina, Sicilia\" class=\"read-more\" href=\"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/\" aria-label=\"Leer m\u00e1s sobre 3\u00aa Asamblea General de SolDAC en Messina, Sicilia\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":22,"featured_media":30862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[461],"tags":[],"class_list":["post-30864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meetings"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3\u00aa Asamblea General de SolDAC en Messina, Sicilia - SolDAC<\/title>\n<meta name=\"description\" content=\"El pasado 29 de febrero y 1 de marzo se llev\u00f3 a cabo la 3\u00aa Asamblea General de SolDAC en Messina. Tuvimos la oportunidad de seguir trabajando juntos, discutiendo sobre la mejor manera de acercar SolDAC a la sociedad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3\u00aa Asamblea General de SolDAC en Messina, Sicilia - SolDAC\" \/>\n<meta property=\"og:description\" content=\"El pasado 29 de febrero y 1 de marzo se llev\u00f3 a cabo la 3\u00aa Asamblea General de SolDAC en Messina. Tuvimos la oportunidad de seguir trabajando juntos, discutiendo sobre la mejor manera de acercar SolDAC a la sociedad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/\" \/>\n<meta property=\"og:site_name\" content=\"SolDAC\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-12T11:47:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-12T12:08:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cintiaescandel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cintiaescandel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/\"},\"author\":{\"name\":\"cintiaescandel\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#\\\/schema\\\/person\\\/66bdc622ff88cc2e1a4a4592386b711f\"},\"headline\":\"3\u00aa Asamblea General de SolDAC en Messina, Sicilia\",\"datePublished\":\"2024-03-12T11:47:36+00:00\",\"dateModified\":\"2024-03-12T12:08:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/\"},\"wordCount\":356,\"publisher\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/03\\\/Foto_grupo_1-scaled.jpg\",\"articleSection\":[\"Meetings\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/\",\"url\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/\",\"name\":\"3\u00aa Asamblea General de SolDAC en Messina, Sicilia - SolDAC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/03\\\/Foto_grupo_1-scaled.jpg\",\"datePublished\":\"2024-03-12T11:47:36+00:00\",\"dateModified\":\"2024-03-12T12:08:43+00:00\",\"description\":\"El pasado 29 de febrero y 1 de marzo se llev\u00f3 a cabo la 3\u00aa Asamblea General de SolDAC en Messina. Tuvimos la oportunidad de seguir trabajando juntos, discutiendo sobre la mejor manera de acercar SolDAC a la sociedad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/03\\\/Foto_grupo_1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/03\\\/Foto_grupo_1-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/3a-asamblea-general-de-soldac-en-messina-sicilia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3\u00aa Asamblea General de SolDAC en Messina, Sicilia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/\",\"name\":\"SolDAC\",\"description\":\"Full Spectrum Solar Direct Air Caputure &amp; Conversion\",\"publisher\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#organization\",\"name\":\"SolDAC\",\"url\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2022\\\/11\\\/SolDAC_Logo_RGB_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/soldac-project.eu\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2022\\\/11\\\/SolDAC_Logo_RGB_COLOR.png\",\"width\":2084,\"height\":693,\"caption\":\"SolDAC\"},\"image\":{\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/#\\\/schema\\\/person\\\/66bdc622ff88cc2e1a4a4592386b711f\",\"name\":\"cintiaescandel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g\",\"caption\":\"cintiaescandel\"},\"url\":\"https:\\\/\\\/soldac-project.eu\\\/es\\\/author\\\/cintiaescandell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3\u00aa Asamblea General de SolDAC en Messina, Sicilia - SolDAC","description":"El pasado 29 de febrero y 1 de marzo se llev\u00f3 a cabo la 3\u00aa Asamblea General de SolDAC en Messina. Tuvimos la oportunidad de seguir trabajando juntos, discutiendo sobre la mejor manera de acercar SolDAC a la sociedad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/","og_locale":"es_ES","og_type":"article","og_title":"3\u00aa Asamblea General de SolDAC en Messina, Sicilia - SolDAC","og_description":"El pasado 29 de febrero y 1 de marzo se llev\u00f3 a cabo la 3\u00aa Asamblea General de SolDAC en Messina. Tuvimos la oportunidad de seguir trabajando juntos, discutiendo sobre la mejor manera de acercar SolDAC a la sociedad.","og_url":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/","og_site_name":"SolDAC","article_published_time":"2024-03-12T11:47:36+00:00","article_modified_time":"2024-03-12T12:08:43+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-scaled.jpg","type":"image\/jpeg"}],"author":"cintiaescandel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cintiaescandel","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/#article","isPartOf":{"@id":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/"},"author":{"name":"cintiaescandel","@id":"https:\/\/soldac-project.eu\/es\/#\/schema\/person\/66bdc622ff88cc2e1a4a4592386b711f"},"headline":"3\u00aa Asamblea General de SolDAC en Messina, Sicilia","datePublished":"2024-03-12T11:47:36+00:00","dateModified":"2024-03-12T12:08:43+00:00","mainEntityOfPage":{"@id":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/"},"wordCount":356,"publisher":{"@id":"https:\/\/soldac-project.eu\/es\/#organization"},"image":{"@id":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/#primaryimage"},"thumbnailUrl":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-scaled.jpg","articleSection":["Meetings"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/","url":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/","name":"3\u00aa Asamblea General de SolDAC en Messina, Sicilia - SolDAC","isPartOf":{"@id":"https:\/\/soldac-project.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/#primaryimage"},"image":{"@id":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/#primaryimage"},"thumbnailUrl":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-scaled.jpg","datePublished":"2024-03-12T11:47:36+00:00","dateModified":"2024-03-12T12:08:43+00:00","description":"El pasado 29 de febrero y 1 de marzo se llev\u00f3 a cabo la 3\u00aa Asamblea General de SolDAC en Messina. Tuvimos la oportunidad de seguir trabajando juntos, discutiendo sobre la mejor manera de acercar SolDAC a la sociedad.","breadcrumb":{"@id":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/#primaryimage","url":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-scaled.jpg","contentUrl":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2024\/03\/Foto_grupo_1-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/soldac-project.eu\/es\/3a-asamblea-general-de-soldac-en-messina-sicilia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soldac-project.eu\/es\/"},{"@type":"ListItem","position":2,"name":"3\u00aa Asamblea General de SolDAC en Messina, Sicilia"}]},{"@type":"WebSite","@id":"https:\/\/soldac-project.eu\/es\/#website","url":"https:\/\/soldac-project.eu\/es\/","name":"SolDAC","description":"Full Spectrum Solar Direct Air Caputure &amp; Conversion","publisher":{"@id":"https:\/\/soldac-project.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soldac-project.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/soldac-project.eu\/es\/#organization","name":"SolDAC","url":"https:\/\/soldac-project.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soldac-project.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2022\/11\/SolDAC_Logo_RGB_COLOR.png","contentUrl":"https:\/\/soldac-project.eu\/wp-content\/uploads\/sites\/25\/2022\/11\/SolDAC_Logo_RGB_COLOR.png","width":2084,"height":693,"caption":"SolDAC"},"image":{"@id":"https:\/\/soldac-project.eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/soldac-project.eu\/es\/#\/schema\/person\/66bdc622ff88cc2e1a4a4592386b711f","name":"cintiaescandel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6331730d5d6bd3e345db09ba77b1c1814082dfe782da038a5d6cbd9b90a3ae5b?s=96&d=mm&r=g","caption":"cintiaescandel"},"url":"https:\/\/soldac-project.eu\/es\/author\/cintiaescandell\/"}]}},"_links":{"self":[{"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/posts\/30864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/comments?post=30864"}],"version-history":[{"count":3,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/posts\/30864\/revisions"}],"predecessor-version":[{"id":30867,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/posts\/30864\/revisions\/30867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/media\/30862"}],"wp:attachment":[{"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/media?parent=30864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/categories?post=30864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soldac-project.eu\/es\/wp-json\/wp\/v2\/tags?post=30864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}